{"id":282,"date":"2015-03-30T09:12:55","date_gmt":"2015-03-30T09:12:55","guid":{"rendered":"https:\/\/www.demenageur-site.com\/blog\/?p=282"},"modified":"2015-03-30T09:12:55","modified_gmt":"2015-03-30T09:12:55","slug":"ajouter-une-authentification-via-htaccess-pour-ladmin-de-wordpress","status":"publish","type":"post","link":"https:\/\/www.demenageur-site.com\/blog\/2015\/03\/ajouter-une-authentification-via-htaccess-pour-ladmin-de-wordpress\/","title":{"rendered":"Ajouter une authentification via htaccess pour l&rsquo;admin de WordPress"},"content":{"rendered":"<p>Au lieu d&rsquo;installer des plugins pas toujours bien maintenus pour prot\u00e9ger l&rsquo;administration de votre site WordPress des acc\u00e8s ind\u00e9sirables, voici une petite astuce toute simple.<br \/>\nLe but est d&rsquo;activer une authentification suppl\u00e9mentaire sur la page de login de votre panel WordPress.<\/p>\n<p>L&rsquo;avantage est que vous pouvez ainsi utiliser les fonctions de monitoring de \u00a0Fail2Ban pour bannir les robots tentant d&rsquo;acc\u00e9der \u00e0 votre back-office.<\/p>\n<p>Editez le fichier .htaccess situ\u00e9 \u00e0 la racine de votre site et ajoutez simplement :<\/p>\n<pre>&lt;FilesMatch \"^(wp-login)\\.php$\"&gt;\r\nAuthType Basic\r\nAuthUserFile \/path\/to\/your\/.htpasswd\r\nAuthName \"Double Authentification Admin WP\"\r\nrequire valid-user\r\n&lt;\/FilesMatch&gt;<\/pre>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au lieu d&rsquo;installer des plugins pas toujours bien maintenus pour prot\u00e9ger l&rsquo;administration de votre site WordPress des acc\u00e8s ind\u00e9sirables, voici une petite astuce toute simple. Le but est d&rsquo;activer une authentification suppl\u00e9mentaire sur la page de login de votre panel<span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.demenageur-site.com\/blog\/2015\/03\/ajouter-une-authentification-via-htaccess-pour-ladmin-de-wordpress\/\">Lire la suite &#8250;<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-linux","category-php-mysql"],"_links":{"self":[{"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":1,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"predecessor-version":[{"id":283,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/posts\/282\/revisions\/283"}],"wp:attachment":[{"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.demenageur-site.com\/blog\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}